{"id":375,"count":16,"description":"As camas de rod\u00edzio j\u00fanior s\u00e3o a op\u00e7\u00e3o mais pr\u00e1tica para quem procura aproveitar ao m\u00e1ximo o espa\u00e7o em quartos modernos. Com uma cama principal e uma cama auxiliar extra\u00edvel, s\u00e3o a solu\u00e7\u00e3o perfeita para quartos partilhados ou para oferecer uma cama extra aos h\u00f3spedes. Al\u00e9m disso, as camas de rod\u00edzio modernas incorporam gavetas ou contentores, tornando-as numa pe\u00e7a de mobili\u00e1rio funcional que combina descanso e arruma\u00e7\u00e3o num \u00fanico design. Ideais para quartos de crian\u00e7as e jovens, as camas de rod\u00edzio destacam-se pela sua versatilidade, conforto e est\u00e9tica moderna, adaptando-se a qualquer estilo de quarto.   ","link":"https:\/\/mueblesorts.com\/pt-pt\/quartos-juvenis\/camas-de-rodizio\/","name":"Camas de rod\u00edzio","slug":"camas-de-rodizio","taxonomy":"product_cat","parent":431,"meta":[],"_links":{"self":[{"href":"https:\/\/mueblesorts.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mueblesorts.com\/pt-pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mueblesorts.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mueblesorts.com\/pt-pt\/wp-json\/wp\/v2\/product_cat\/431"}],"wp:post_type":[{"href":"https:\/\/mueblesorts.com\/pt-pt\/wp-json\/wp\/v2\/product?product_cat=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}