{"id":374,"count":16,"description":"Les lits gigognes junior sont l'option la plus pratique pour ceux qui cherchent \u00e0 optimiser l'espace dans les chambres modernes. Avec un lit principal et un lit auxiliaire escamotable, ils offrent une solution parfaite pour les chambres partag\u00e9es ou pour fournir un lit suppl\u00e9mentaire aux invit\u00e9s. En outre, les lits gigognes modernes int\u00e8grent des tiroirs ou des conteneurs, ce qui en fait un meuble fonctionnel qui allie repos et rangement dans un seul et m\u00eame design. Id\u00e9aux pour les chambres d'enfants et de jeunes, les lits gigognes se distinguent par leur polyvalence, leur confort et leur esth\u00e9tique moderne, s'adaptant \u00e0 tous les styles de chambres.   ","link":"https:\/\/mueblesorts.com\/fr\/chambres-pour-adolescents\/lits-gigognes\/","name":"Lits gigognes","slug":"lits-gigognes","taxonomy":"product_cat","parent":429,"meta":[],"_links":{"self":[{"href":"https:\/\/mueblesorts.com\/fr\/wp-json\/wp\/v2\/product_cat\/374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mueblesorts.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mueblesorts.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mueblesorts.com\/fr\/wp-json\/wp\/v2\/product_cat\/429"}],"wp:post_type":[{"href":"https:\/\/mueblesorts.com\/fr\/wp-json\/wp\/v2\/product?product_cat=374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}